{"id":475,"date":"2020-06-02T15:16:08","date_gmt":"2020-06-02T15:16:08","guid":{"rendered":"https:\/\/visit-sibenik.com\/?page_id=475"},"modified":"2025-05-16T07:45:48","modified_gmt":"2025-05-16T07:45:48","slug":"swimming-tour","status":"publish","type":"page","link":"https:\/\/visit-sibenik.com\/de\/swimming-tour\/","title":{"rendered":"Schwimmen Tour"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"475\" class=\"elementor elementor-475\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c0b8c2a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"c0b8c2a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-30fa20f7\" data-id=\"30fa20f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3050ad6b elementor-widget elementor-widget-image\" data-id=\"3050ad6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/visit-sibenik.com\/home\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"54\" src=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/05\/logoan.png\" class=\"attachment-large size-large wp-image-11\" alt=\"\" srcset=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/05\/logoan.png 309w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/05\/logoan-300x52.png 300w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-783a6729\" data-id=\"783a6729\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-511a8566 elementor-nav-menu__align-end elementor-nav-menu--stretch elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"511a8566\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;full_width&quot;:&quot;stretch&quot;,&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-slide\">\n\t\t\t\t<ul id=\"menu-1-511a8566\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-85\"><a href=\"https:\/\/visit-sibenik.com\/de\/\" class=\"elementor-item\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-877\"><a href=\"https:\/\/visit-sibenik.com\/de\/adventures\/\" class=\"elementor-item\">Adventures<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1694\"><a href=\"https:\/\/visit-sibenik.com\/de\/new-speedboat-tour-with-anima-natura\/\" class=\"elementor-sub-item\">NEW! Speedboat Tour with Anima Natura<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-509\"><a href=\"https:\/\/visit-sibenik.com\/de\/speed-boat-tour-krka\/\" class=\"elementor-sub-item\">Speed Boat Tour to Krka<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-508\"><a href=\"https:\/\/visit-sibenik.com\/de\/speed-boat-tour-kornati\/\" class=\"elementor-sub-item\">NP Kornati Speed boat tour<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-507\"><a href=\"https:\/\/visit-sibenik.com\/de\/riviera-tour-zlarin-prvic-tijat\/\" class=\"elementor-sub-item\">Riviera Tour: Zlarin + Prvi\u0107 + Tijat<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-506\"><a href=\"https:\/\/visit-sibenik.com\/de\/swimming-tour\/\" class=\"elementor-sub-item\">Swimming Tour<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1609\"><a href=\"https:\/\/visit-sibenik.com\/de\/sibenik-lux-islands-picnic-boat-tour\/\" class=\"elementor-sub-item\">\u0160ibenik Lux Islands Picnic Boat Tour<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1608\"><a href=\"https:\/\/visit-sibenik.com\/de\/la-dolce-vita-tour-experience-the-dream-mediterranean\/\" class=\"elementor-sub-item\">La Dolce Vita Tour \u2013 Experience the Dream Mediterranean!<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-505\"><a href=\"https:\/\/visit-sibenik.com\/de\/panoramic-boat-tour\/\" class=\"elementor-sub-item\">Panoramic Boat Tour<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-504\"><a href=\"https:\/\/visit-sibenik.com\/de\/private-boat-tour\/\" class=\"elementor-sub-item\">Private Boat Tour<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-503\"><a href=\"https:\/\/visit-sibenik.com\/de\/kornati-big-boat\/\" class=\"elementor-sub-item\">Kornati Big Boat<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1204\"><a href=\"https:\/\/visit-sibenik.com\/de\/krka-big-boat\/\" class=\"elementor-sub-item\">Krka Big Boat<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-789\"><a href=\"https:\/\/visit-sibenik.com\/de\/blue-cave\/\" class=\"elementor-sub-item\">Blue Cave<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-502\"><a href=\"https:\/\/visit-sibenik.com\/de\/plitvice-lakes\/\" class=\"elementor-sub-item\">Plitvice Lakes<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-501\"><a href=\"https:\/\/visit-sibenik.com\/de\/roski-slap\/\" class=\"elementor-sub-item\">Ro\u0161ki Slap<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-500\"><a href=\"https:\/\/visit-sibenik.com\/de\/sibenik-walking-tour\/\" class=\"elementor-sub-item\">\u0160ibenik Walking Tour<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-499\"><a href=\"https:\/\/visit-sibenik.com\/de\/wine-tasting\/\" class=\"elementor-sub-item\">Wine Tasting<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1093\"><a href=\"https:\/\/visit-sibenik.com\/de\/event\/\" class=\"elementor-sub-item\">Event<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-83\"><a href=\"https:\/\/visit-sibenik.com\/de\/accommodation\/\" class=\"elementor-item\">Accommodation<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-416\"><a href=\"https:\/\/visit-sibenik.com\/de\/transfers\/\" class=\"elementor-item\">Transfers<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-818\"><a href=\"https:\/\/visit-sibenik.com\/de\/rent-a-boat\/\" class=\"elementor-item\">Rent a boat<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-81\"><a href=\"https:\/\/visit-sibenik.com\/de\/prices\/\" class=\"elementor-item\">Prices<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1676\"><a href=\"https:\/\/visit-sibenik.com\/de\/about-us\/\" class=\"elementor-item\">About us<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-82\"><a href=\"https:\/\/visit-sibenik.com\/de\/contact\/\" class=\"elementor-item\">Contact<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1042\"><a href=\"https:\/\/visit-sibenik.com\/de\/news\/\" class=\"elementor-item\">News<\/a><\/li>\n<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher menu-item-has-children current-language-menu-item menu-item-1565\"><a href=\"https:\/\/visit-sibenik.com\/de\/wp-json\/wp\/v2\/pages\/475#TRPLINKPROCESSED\" class=\"elementor-item elementor-item-anchor\"><span data-no-translation><img decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/visit-sibenik.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/de_DE.png\" width=\"18\" height=\"12\" alt=\"de_DE\" title=\"German\"><span class=\"trp-ls-language-name\">DE<\/span><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-1566\"><a href=\"https:\/\/visit-sibenik.com\/de\/wp-json\/wp\/v2\/pages\/475#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor\"><span data-no-translation><img decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/visit-sibenik.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/en_GB.png\" width=\"18\" height=\"12\" alt=\"en_GB\" title=\"English\"><span class=\"trp-ls-language-name\">EN<\/span><\/span><\/a><\/li>\n\t<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-1562\"><a href=\"https:\/\/visit-sibenik.com\/de\/wp-json\/wp\/v2\/pages\/475#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor\"><span data-no-translation><img loading=\"lazy\" decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/visit-sibenik.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/hr.png\" width=\"18\" height=\"12\" alt=\"hr\" title=\"Croatian\"><span class=\"trp-ls-language-name\">HR<\/span><\/span><\/a><\/li>\n\t<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-1560\"><a href=\"https:\/\/visit-sibenik.com\/de\/wp-json\/wp\/v2\/pages\/475#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor\"><span data-no-translation><img loading=\"lazy\" decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/visit-sibenik.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/cs_CZ.png\" width=\"18\" height=\"12\" alt=\"cs_CZ\" title=\"Czech\"><span class=\"trp-ls-language-name\">CS<\/span><\/span><\/a><\/li>\n\t<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-1585\"><a href=\"https:\/\/visit-sibenik.com\/de\/wp-json\/wp\/v2\/pages\/475#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor\"><span data-no-translation><img loading=\"lazy\" decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/visit-sibenik.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/fr_FR.png\" width=\"18\" height=\"12\" alt=\"fr_FR\" title=\"French\"><span class=\"trp-ls-language-name\">FR<\/span><\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Men\u00fc Umschalter\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-511a8566\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-85\"><a href=\"https:\/\/visit-sibenik.com\/de\/\" class=\"elementor-item\" tabindex=\"-1\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-877\"><a href=\"https:\/\/visit-sibenik.com\/de\/adventures\/\" class=\"elementor-item\" tabindex=\"-1\">Adventures<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1694\"><a href=\"https:\/\/visit-sibenik.com\/de\/new-speedboat-tour-with-anima-natura\/\" class=\"elementor-sub-item\" tabindex=\"-1\">NEW! Speedboat Tour with Anima Natura<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-509\"><a href=\"https:\/\/visit-sibenik.com\/de\/speed-boat-tour-krka\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Speed Boat Tour to Krka<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-508\"><a href=\"https:\/\/visit-sibenik.com\/de\/speed-boat-tour-kornati\/\" class=\"elementor-sub-item\" tabindex=\"-1\">NP Kornati Speed boat tour<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-507\"><a href=\"https:\/\/visit-sibenik.com\/de\/riviera-tour-zlarin-prvic-tijat\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Riviera Tour: Zlarin + Prvi\u0107 + Tijat<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-506\"><a href=\"https:\/\/visit-sibenik.com\/de\/swimming-tour\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Swimming Tour<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1609\"><a href=\"https:\/\/visit-sibenik.com\/de\/sibenik-lux-islands-picnic-boat-tour\/\" class=\"elementor-sub-item\" tabindex=\"-1\">\u0160ibenik Lux Islands Picnic Boat Tour<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1608\"><a href=\"https:\/\/visit-sibenik.com\/de\/la-dolce-vita-tour-experience-the-dream-mediterranean\/\" class=\"elementor-sub-item\" tabindex=\"-1\">La Dolce Vita Tour \u2013 Experience the Dream Mediterranean!<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-505\"><a href=\"https:\/\/visit-sibenik.com\/de\/panoramic-boat-tour\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Panoramic Boat Tour<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-504\"><a href=\"https:\/\/visit-sibenik.com\/de\/private-boat-tour\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Private Boat Tour<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-503\"><a href=\"https:\/\/visit-sibenik.com\/de\/kornati-big-boat\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Kornati Big Boat<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1204\"><a href=\"https:\/\/visit-sibenik.com\/de\/krka-big-boat\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Krka Big Boat<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-789\"><a href=\"https:\/\/visit-sibenik.com\/de\/blue-cave\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Blue Cave<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-502\"><a href=\"https:\/\/visit-sibenik.com\/de\/plitvice-lakes\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Plitvice Lakes<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-501\"><a href=\"https:\/\/visit-sibenik.com\/de\/roski-slap\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Ro\u0161ki Slap<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-500\"><a href=\"https:\/\/visit-sibenik.com\/de\/sibenik-walking-tour\/\" class=\"elementor-sub-item\" tabindex=\"-1\">\u0160ibenik Walking Tour<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-499\"><a href=\"https:\/\/visit-sibenik.com\/de\/wine-tasting\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Wine Tasting<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1093\"><a href=\"https:\/\/visit-sibenik.com\/de\/event\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Event<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-83\"><a href=\"https:\/\/visit-sibenik.com\/de\/accommodation\/\" class=\"elementor-item\" tabindex=\"-1\">Accommodation<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-416\"><a href=\"https:\/\/visit-sibenik.com\/de\/transfers\/\" class=\"elementor-item\" tabindex=\"-1\">Transfers<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-818\"><a href=\"https:\/\/visit-sibenik.com\/de\/rent-a-boat\/\" class=\"elementor-item\" tabindex=\"-1\">Rent a boat<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-81\"><a href=\"https:\/\/visit-sibenik.com\/de\/prices\/\" class=\"elementor-item\" tabindex=\"-1\">Prices<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1676\"><a href=\"https:\/\/visit-sibenik.com\/de\/about-us\/\" class=\"elementor-item\" tabindex=\"-1\">About us<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-82\"><a href=\"https:\/\/visit-sibenik.com\/de\/contact\/\" class=\"elementor-item\" tabindex=\"-1\">Contact<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1042\"><a href=\"https:\/\/visit-sibenik.com\/de\/news\/\" class=\"elementor-item\" tabindex=\"-1\">News<\/a><\/li>\n<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher menu-item-has-children current-language-menu-item menu-item-1565\"><a href=\"https:\/\/visit-sibenik.com\/de\/wp-json\/wp\/v2\/pages\/475#TRPLINKPROCESSED\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\"><span data-no-translation><img decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/visit-sibenik.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/de_DE.png\" width=\"18\" height=\"12\" alt=\"de_DE\" title=\"German\"><span class=\"trp-ls-language-name\">DE<\/span><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-1566\"><a href=\"https:\/\/visit-sibenik.com\/de\/wp-json\/wp\/v2\/pages\/475#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\"><span data-no-translation><img decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/visit-sibenik.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/en_GB.png\" width=\"18\" height=\"12\" alt=\"en_GB\" title=\"English\"><span class=\"trp-ls-language-name\">EN<\/span><\/span><\/a><\/li>\n\t<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-1562\"><a href=\"https:\/\/visit-sibenik.com\/de\/wp-json\/wp\/v2\/pages\/475#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\"><span data-no-translation><img loading=\"lazy\" decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/visit-sibenik.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/hr.png\" width=\"18\" height=\"12\" alt=\"hr\" title=\"Croatian\"><span class=\"trp-ls-language-name\">HR<\/span><\/span><\/a><\/li>\n\t<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-1560\"><a href=\"https:\/\/visit-sibenik.com\/de\/wp-json\/wp\/v2\/pages\/475#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\"><span data-no-translation><img loading=\"lazy\" decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/visit-sibenik.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/cs_CZ.png\" width=\"18\" height=\"12\" alt=\"cs_CZ\" title=\"Czech\"><span class=\"trp-ls-language-name\">CS<\/span><\/span><\/a><\/li>\n\t<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-1585\"><a href=\"https:\/\/visit-sibenik.com\/de\/wp-json\/wp\/v2\/pages\/475#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\"><span data-no-translation><img loading=\"lazy\" decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/visit-sibenik.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/fr_FR.png\" width=\"18\" height=\"12\" alt=\"fr_FR\" title=\"French\"><span class=\"trp-ls-language-name\">FR<\/span><\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-51ca54b4 elementor-section-height-full elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"51ca54b4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-526b91ed\" data-id=\"526b91ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4db43378 elementor-widget elementor-widget-heading\" data-id=\"4db43378\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">Swimming Tour<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55593a62 elementor-widget elementor-widget-heading\" data-id=\"55593a62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-large\">Join us on our original two-hour swimming trip and enjoy hidden spots on \u0160ibenik\u2019s islands. Visit the \u0160ibenik archipelago, enjoy its islands in all their splendour and explore them as a local.<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a836919 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3a836919\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/visit-sibenik.com\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Book Now<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-20c3c90c elementor-section-height-min-height elementor-section-items-stretch elementor-section-full_width elementor-section-height-default\" data-id=\"20c3c90c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-729e13a3\" data-id=\"729e13a3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-418a7cf4 elementor-align-start elementor-widget__width-auto elementor-absolute elementor-hidden-phone elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"418a7cf4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/web.facebook.com\/visitsibenik\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook-f\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/visitsibenik\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Capa_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 512 512\" style=\"enable-background:new 0 0 512 512;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M352,0H160C71.648,0,0,71.648,0,160v192c0,88.352,71.648,160,160,160h192c88.352,0,160-71.648,160-160V160    C512,71.648,440.352,0,352,0z M464,352c0,61.76-50.24,112-112,112H160c-61.76,0-112-50.24-112-112V160C48,98.24,98.24,48,160,48    h192c61.76,0,112,50.24,112,112V352z\"><\/path>\t<\/g><\/g><g>\t<g>\t\t<path d=\"M256,128c-70.688,0-128,57.312-128,128s57.312,128,128,128s128-57.312,128-128S326.688,128,256,128z M256,336    c-44.096,0-80-35.904-80-80c0-44.128,35.904-80,80-80s80,35.872,80,80C336,300.096,300.096,336,256,336z\"><\/path>\t<\/g><\/g><g>\t<g>\t\t<circle cx=\"393.6\" cy=\"118.4\" r=\"17.056\"><\/circle>\t<\/g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.youtube.com\/channel\/UCOdQaLgTP4WK7srvCwCrPuw\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3f8a6653\" data-id=\"3f8a6653\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ae73287 elementor-widget elementor-widget-heading\" data-id=\"ae73287\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Swimming Tour<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29fc0e2a elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"29fc0e2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 20 16&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;2.2&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cg transform=&#039;translate(-12.000000, 0)&#039;%3E%3Cpath d=&#039;M28,0L10,18&#039;\/%3E%3Cpath d=&#039;M18,0L0,18&#039;\/%3E%3Cpath d=&#039;M48,0L30,18&#039;\/%3E%3Cpath d=&#039;M38,0L20,18&#039;\/%3E%3C\/g%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-242a076c elementor-widget elementor-widget-heading\" data-id=\"242a076c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">About the tour<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60b9573b elementor-widget elementor-widget-text-editor\" data-id=\"60b9573b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Join us on our original two-hour swimming trip and enjoy hidden spots on \u0160ibenik\u2019s islands. Visit the \u0160ibenik archipelago, enjoy its islands in all their splendour and explore them as a local.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6c0deda0\" data-id=\"6c0deda0\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;2&quot;,&quot;sizes&quot;:[]},&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32d949a1 elementor-widget elementor-widget-spacer\" data-id=\"32d949a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-25d103b8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"25d103b8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4b4b963a\" data-id=\"4b4b963a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-749fb91a elementor-widget elementor-widget-heading\" data-id=\"749fb91a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Itinerary \/ schedule<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2da2502f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2da2502f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ad88132\" data-id=\"ad88132\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1050df0a elementor-widget elementor-widget-heading\" data-id=\"1050df0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">09:00h - 11:00h<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-36e256f9\" data-id=\"36e256f9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-380a3486 elementor-widget elementor-widget-heading\" data-id=\"380a3486\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Departure from \u0160ibenik<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1492db64 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1492db64\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-65041ba9\" data-id=\"65041ba9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e8a4c7e elementor-widget elementor-widget-heading\" data-id=\"e8a4c7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">11:00h - 13:00h<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5e0be3f8\" data-id=\"5e0be3f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58e367fe elementor-widget elementor-widget-heading\" data-id=\"58e367fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Departure from \u0160ibenik<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-227b9402 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"227b9402\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-43d4082a\" data-id=\"43d4082a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a875641 elementor-widget elementor-widget-heading\" data-id=\"4a875641\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">13:00h - 15:00h<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-18bbb530\" data-id=\"18bbb530\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b142c62 elementor-widget elementor-widget-heading\" data-id=\"1b142c62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Departure from \u0160ibenik<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-625f869b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"625f869b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6ca6bd6d\" data-id=\"6ca6bd6d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2801e12d elementor-widget elementor-widget-heading\" data-id=\"2801e12d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">15:00h - 17:00h<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fd00c77\" data-id=\"fd00c77\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-298a761d elementor-widget elementor-widget-heading\" data-id=\"298a761d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Departure from \u0160ibenik<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4607cce0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4607cce0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2eec1cfe\" data-id=\"2eec1cfe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1555df21 elementor-widget elementor-widget-heading\" data-id=\"1555df21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">17:00h - 19h:00h<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fce5e6\" data-id=\"fce5e6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e475a6 elementor-widget elementor-widget-heading\" data-id=\"5e475a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Departure from \u0160ibenik<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ef5e23f\" data-id=\"ef5e23f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-763db2bf elementor-widget elementor-widget-heading\" data-id=\"763db2bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Price<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39fee215 elementor-widget elementor-widget-heading\" data-id=\"39fee215\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Per person 50,00 \u20ac<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd46995 elementor-widget elementor-widget-heading\" data-id=\"fd46995\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Per child (5 - 12 years) 30,00 \u20ac<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d78bab0 elementor-widget elementor-widget-heading\" data-id=\"d78bab0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Per child (0 - 5 years) free<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e3891fa elementor-widget elementor-widget-heading\" data-id=\"3e3891fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Included in price<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-793641f2 elementor-widget elementor-widget-heading\" data-id=\"793641f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Skipper boat<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29db1af5 elementor-widget elementor-widget-heading\" data-id=\"29db1af5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Swimming time<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a39e581 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a39e581\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-690ae9e5\" data-id=\"690ae9e5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-355600e elementor-widget elementor-widget-heading\" data-id=\"355600e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Get a better view<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3707b282 elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"3707b282\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-518e8de0\" data-id=\"518e8de0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fbc0f63 elementor-skin-coverflow elementor-arrows-yes elementor-pagination-type-bullets elementor-pagination-position-outside elementor-widget elementor-widget-media-carousel\" data-id=\"5fbc0f63\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;skin&quot;:&quot;coverflow&quot;,&quot;slides_to_scroll&quot;:&quot;3&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositives\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"rsz_sib2\" style=\"background-image: url(&#039;https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib2-scaled.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"rsz_sib1\" style=\"background-image: url(&#039;https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Pr\u00e9c\u00e9dent\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Suivant\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-37ccbfb2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"37ccbfb2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-78c9600d\" data-id=\"78c9600d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a4c09d1 elementor-widget elementor-widget-heading\" data-id=\"6a4c09d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">See our other adventures<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a201a47 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3a201a47\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b895590\" data-id=\"b895590\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49942a3b elementor-grid-6 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-portfolio\" data-id=\"49942a3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:&quot;6&quot;,&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;item_ratio&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;item_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"portfolio.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-portfolio elementor-grid elementor-posts-container\" role=\"list\">\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-479 page type-page status-publish has-post-thumbnail hentry entry has-media\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/visit-sibenik.com\/de\/private-boat-tour\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"749\" src=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/07\/Screenshot_20200629_122159-1024x749.jpg\" class=\"attachment-large size-large wp-image-1114\" alt=\"\" srcset=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/07\/Screenshot_20200629_122159-1024x749.jpg 1024w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/07\/Screenshot_20200629_122159-300x219.jpg 300w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/07\/Screenshot_20200629_122159-768x562.jpg 768w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/07\/Screenshot_20200629_122159.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPrivate Boat Tour\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-489 page type-page status-publish has-post-thumbnail hentry entry has-media\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/visit-sibenik.com\/de\/wine-tasting\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"754\" src=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/Screenshot_20200605_115745-1024x754.jpg\" class=\"attachment-large size-large wp-image-921\" alt=\"\" srcset=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/Screenshot_20200605_115745-1024x754.jpg 1024w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/Screenshot_20200605_115745-300x221.jpg 300w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/Screenshot_20200605_115745-768x565.jpg 768w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/Screenshot_20200605_115745.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tWine Tasting\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-487 page type-page status-publish has-post-thumbnail hentry entry has-media\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/visit-sibenik.com\/de\/sibenik-walking-tour\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/3min-1024x575-1.jpg\" class=\"attachment-large size-large wp-image-189\" alt=\"\" srcset=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/3min-1024x575-1.jpg 1024w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/3min-1024x575-1-300x168.jpg 300w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/3min-1024x575-1-768x431.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\t\u0160ibenik Walking Tour\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-786 page type-page status-publish has-post-thumbnail hentry entry has-media\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/visit-sibenik.com\/de\/blue-cave\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/IMG_20200322_185512_720-1024x1024.jpg\" class=\"attachment-large size-large wp-image-1046\" alt=\"\" srcset=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/IMG_20200322_185512_720-1024x1024.jpg 1024w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/IMG_20200322_185512_720-300x300.jpg 300w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/IMG_20200322_185512_720-150x150.jpg 150w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/IMG_20200322_185512_720-768x768.jpg 768w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/IMG_20200322_185512_720.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tBlue Cave\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-485 page type-page status-publish has-post-thumbnail hentry entry has-media\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/visit-sibenik.com\/de\/roski-slap\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_roski-slap-tiny-1024x683.jpg\" class=\"attachment-large size-large wp-image-904\" alt=\"\" srcset=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_roski-slap-tiny-1024x683.jpg 1024w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_roski-slap-tiny-300x200.jpg 300w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_roski-slap-tiny-768x512.jpg 768w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_roski-slap-tiny-1536x1024.jpg 1536w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_roski-slap-tiny-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tRo\u0161ki Slap\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-471 page type-page status-publish has-post-thumbnail hentry entry has-media\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/visit-sibenik.com\/de\/speed-boat-tour-kornati\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"709\" src=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib3-1024x709.jpg\" class=\"attachment-large size-large wp-image-901\" alt=\"\" srcset=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib3-1024x709.jpg 1024w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib3-300x208.jpg 300w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib3-768x532.jpg 768w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib3-1536x1063.jpg 1536w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib3-2048x1418.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tSpeed Boat Tour Kornati\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-483 page type-page status-publish has-post-thumbnail hentry entry has-media\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/visit-sibenik.com\/de\/plitvice-lakes\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/plitvice_min-1024x682-1.jpg\" class=\"attachment-large size-large wp-image-200\" alt=\"\" srcset=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/plitvice_min-1024x682-1.jpg 1024w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/plitvice_min-1024x682-1-300x200.jpg 300w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/plitvice_min-1024x682-1-768x512.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPlitvice Lakes\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-475 page type-page status-publish has-post-thumbnail hentry entry has-media\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/visit-sibenik.com\/de\/swimming-tour\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"691\" height=\"1024\" src=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib2-691x1024.jpg\" class=\"attachment-large size-large wp-image-899\" alt=\"\" srcset=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib2-691x1024.jpg 691w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib2-202x300.jpg 202w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib2-768x1139.jpg 768w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib2-1036x1536.jpg 1036w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib2-1381x2048.jpg 1381w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib2-scaled.jpg 1726w\" sizes=\"(max-width: 691px) 100vw, 691px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tSwimming Tour\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-469 page type-page status-publish has-post-thumbnail hentry entry has-media\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/visit-sibenik.com\/de\/speed-boat-tour-krka\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2024\/05\/image00012-768x1024.jpeg\" class=\"attachment-large size-large wp-image-1428\" alt=\"\" srcset=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2024\/05\/image00012-768x1024.jpeg 768w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2024\/05\/image00012-225x300.jpeg 225w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2024\/05\/image00012-1152x1536.jpeg 1152w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2024\/05\/image00012-1536x2048.jpeg 1536w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2024\/05\/image00012-scaled.jpeg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tSpeed Boat Tour Krka\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-481 page type-page status-publish has-post-thumbnail hentry entry has-media\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/visit-sibenik.com\/de\/kornati-big-boat\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/kornati-new-1-1024x682.jpg\" class=\"attachment-large size-large wp-image-773\" alt=\"\" srcset=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/kornati-new-1-1024x682.jpg 1024w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/kornati-new-1-300x200.jpg 300w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/kornati-new-1-768x512.jpg 768w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/kornati-new-1-1536x1023.jpg 1536w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/kornati-new-1-2048x1364.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tKornati Big Boat\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-473 page type-page status-publish has-post-thumbnail hentry entry has-media\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/visit-sibenik.com\/de\/riviera-tour-zlarin-prvic-tijat\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib1-768x1024.jpg\" class=\"attachment-large size-large wp-image-900\" alt=\"\" srcset=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib1-768x1024.jpg 768w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib1-225x300.jpg 225w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib1-1152x1536.jpg 1152w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib1.jpg 1500w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tRiviera Tour: Zlarin + Prvi\u0107 + Tijat\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-491 page type-page status-publish has-post-thumbnail hentry entry has-media\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/visit-sibenik.com\/de\/fishing-trip-with-boat-and-kayaks\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"680\" src=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/fishing-trip-1024x680.jpg\" class=\"attachment-large size-large wp-image-218\" alt=\"\" srcset=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/fishing-trip-1024x680.jpg 1024w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/fishing-trip-300x199.jpg 300w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/fishing-trip-768x510.jpg 768w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/fishing-trip.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tFishing Trip With Boat And Kayaks\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-378a8cc6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"378a8cc6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2b4489d3\" data-id=\"2b4489d3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e429191 elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4e429191\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Instagram<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-43bdc75d\" data-id=\"43bdc75d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39fa044a elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"39fa044a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-heart\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52c8505c elementor-widget elementor-widget-heading\" data-id=\"52c8505c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Visit \u0160ibenik<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a8f606a elementor-widget elementor-widget-heading\" data-id=\"1a8f606a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0160IBENIK is an adventure waiting to happen. It is a town FULL OF LOVE. Be sure to book your guided tour with ANIMA NATURA today.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-41568a04\" data-id=\"41568a04\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37ccebb3 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"37ccebb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook-f\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Facebook<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-271a4c07 elementor-widget elementor-widget-facebook-page\" data-id=\"271a4c07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"facebook-page.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-facebook-widget fb-page\" data-href=\"https:\/\/web.facebook.com\/visitsibenik\/?_rdc=1&amp;_rdr\" data-tabs=\"timeline\" data-height=\"350px\" data-width=\"500px\" data-small-header=\"false\" data-hide-cover=\"false\" data-show-facepile=\"true\" data-hide-cta=\"false\" style=\"min-height: 1px;height:350px\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Swimming Tour Join us on our original two-hour swimming trip and enjoy hidden spots on \u0160ibenik\u2019s islands. Visit the \u0160ibenik archipelago, enjoy its islands in all their splendour and explore them as a local. Book Now Swimming Tour About the tour Join us on our original two-hour swimming trip and enjoy hidden spots on \u0160ibenik\u2019s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":899,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ocean_post_layout":"full-screen","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"off","ocean_display_header":"off","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"on","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"off","ocean_display_footer_bottom":"off","ocean_custom_footer_template":"0","footnotes":""},"class_list":["post-475","page","type-page","status-publish","has-post-thumbnail","hentry","entry","has-media"],"_links":{"self":[{"href":"https:\/\/visit-sibenik.com\/de\/wp-json\/wp\/v2\/pages\/475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit-sibenik.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/visit-sibenik.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/visit-sibenik.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visit-sibenik.com\/de\/wp-json\/wp\/v2\/comments?post=475"}],"version-history":[{"count":28,"href":"https:\/\/visit-sibenik.com\/de\/wp-json\/wp\/v2\/pages\/475\/revisions"}],"predecessor-version":[{"id":1667,"href":"https:\/\/visit-sibenik.com\/de\/wp-json\/wp\/v2\/pages\/475\/revisions\/1667"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit-sibenik.com\/de\/wp-json\/wp\/v2\/media\/899"}],"wp:attachment":[{"href":"https:\/\/visit-sibenik.com\/de\/wp-json\/wp\/v2\/media?parent=475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}