{"id":481,"date":"2020-06-02T15:17:21","date_gmt":"2020-06-02T15:17:21","guid":{"rendered":"https:\/\/visit-sibenik.com\/?page_id=481"},"modified":"2025-05-16T06:57:02","modified_gmt":"2025-05-16T06:57:02","slug":"kornati-big-boat","status":"publish","type":"page","link":"https:\/\/visit-sibenik.com\/fr\/kornati-big-boat\/","title":{"rendered":"Excursion des Kornati en grand bateau"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"481\" class=\"elementor elementor-481\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2e2f5f6 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2e2f5f6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3ec1f647\" data-id=\"3ec1f647\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65ffeda2 elementor-widget elementor-widget-image\" data-id=\"65ffeda2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/visit-sibenik.com\/home\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"54\" src=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/05\/logoan.png\" class=\"attachment-large size-large wp-image-11\" alt=\"\" srcset=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/05\/logoan.png 309w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/05\/logoan-300x52.png 300w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1ae174b3\" data-id=\"1ae174b3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15d80cfb elementor-nav-menu__align-end elementor-nav-menu--stretch elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"15d80cfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;full_width&quot;:&quot;stretch&quot;,&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-slide\">\n\t\t\t\t<ul id=\"menu-1-15d80cfb\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-85\"><a href=\"https:\/\/visit-sibenik.com\/fr\/\" class=\"elementor-item\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-877\"><a href=\"https:\/\/visit-sibenik.com\/fr\/adventures\/\" class=\"elementor-item\">Adventures<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1694\"><a href=\"https:\/\/visit-sibenik.com\/fr\/new-speedboat-tour-with-anima-natura\/\" class=\"elementor-sub-item\">NEW! Speedboat Tour with Anima Natura<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-509\"><a href=\"https:\/\/visit-sibenik.com\/fr\/speed-boat-tour-krka\/\" class=\"elementor-sub-item\">Speed Boat Tour to Krka<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-508\"><a href=\"https:\/\/visit-sibenik.com\/fr\/speed-boat-tour-kornati\/\" class=\"elementor-sub-item\">NP Kornati Speed boat tour<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-507\"><a href=\"https:\/\/visit-sibenik.com\/fr\/riviera-tour-zlarin-prvic-tijat\/\" class=\"elementor-sub-item\">Riviera Tour: Zlarin + Prvi\u0107 + Tijat<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-506\"><a href=\"https:\/\/visit-sibenik.com\/fr\/swimming-tour\/\" class=\"elementor-sub-item\">Swimming Tour<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1609\"><a href=\"https:\/\/visit-sibenik.com\/fr\/sibenik-lux-islands-picnic-boat-tour\/\" class=\"elementor-sub-item\">\u0160ibenik Lux Islands Picnic Boat Tour<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1608\"><a href=\"https:\/\/visit-sibenik.com\/fr\/la-dolce-vita-tour-experience-the-dream-mediterranean\/\" class=\"elementor-sub-item\">La Dolce Vita Tour \u2013 Experience the Dream Mediterranean!<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-505\"><a href=\"https:\/\/visit-sibenik.com\/fr\/panoramic-boat-tour\/\" class=\"elementor-sub-item\">Panoramic Boat Tour<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-504\"><a href=\"https:\/\/visit-sibenik.com\/fr\/private-boat-tour\/\" class=\"elementor-sub-item\">Private Boat Tour<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-503\"><a href=\"https:\/\/visit-sibenik.com\/fr\/kornati-big-boat\/\" class=\"elementor-sub-item\">Kornati Big Boat<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1204\"><a href=\"https:\/\/visit-sibenik.com\/fr\/krka-big-boat\/\" class=\"elementor-sub-item\">Krka Big Boat<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-789\"><a href=\"https:\/\/visit-sibenik.com\/fr\/blue-cave\/\" class=\"elementor-sub-item\">Blue Cave<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-502\"><a href=\"https:\/\/visit-sibenik.com\/fr\/plitvice-lakes\/\" class=\"elementor-sub-item\">Plitvice Lakes<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-501\"><a href=\"https:\/\/visit-sibenik.com\/fr\/roski-slap\/\" class=\"elementor-sub-item\">Ro\u0161ki Slap<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-500\"><a href=\"https:\/\/visit-sibenik.com\/fr\/sibenik-walking-tour\/\" class=\"elementor-sub-item\">\u0160ibenik Walking Tour<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-499\"><a href=\"https:\/\/visit-sibenik.com\/fr\/wine-tasting\/\" class=\"elementor-sub-item\">Wine Tasting<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1093\"><a href=\"https:\/\/visit-sibenik.com\/fr\/event\/\" class=\"elementor-sub-item\">Event<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-83\"><a href=\"https:\/\/visit-sibenik.com\/fr\/accommodation\/\" class=\"elementor-item\">Accommodation<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-416\"><a href=\"https:\/\/visit-sibenik.com\/fr\/transfers\/\" class=\"elementor-item\">Transfers<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-818\"><a href=\"https:\/\/visit-sibenik.com\/fr\/rent-a-boat\/\" class=\"elementor-item\">Rent a boat<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-81\"><a href=\"https:\/\/visit-sibenik.com\/fr\/prices\/\" class=\"elementor-item\">Prices<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1676\"><a href=\"https:\/\/visit-sibenik.com\/fr\/about-us\/\" class=\"elementor-item\">About us<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-82\"><a href=\"https:\/\/visit-sibenik.com\/fr\/contact\/\" class=\"elementor-item\">Contact<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1042\"><a href=\"https:\/\/visit-sibenik.com\/fr\/news\/\" class=\"elementor-item\">News<\/a><\/li>\n<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher menu-item-has-children current-language-menu-item menu-item-1565\"><a href=\"https:\/\/visit-sibenik.com\/fr\/wp-json\/wp\/v2\/pages\/481#TRPLINKPROCESSED\" class=\"elementor-item elementor-item-anchor\"><span data-no-translation><img decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/visit-sibenik.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/fr_FR.png\" width=\"18\" height=\"12\" alt=\"fr_FR\" title=\"French\"><span class=\"trp-ls-language-name\">FR<\/span><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-1566\"><a href=\"https:\/\/visit-sibenik.com\/fr\/wp-json\/wp\/v2\/pages\/481#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor\"><span data-no-translation><img decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/visit-sibenik.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/en_GB.png\" width=\"18\" height=\"12\" alt=\"en_GB\" title=\"English\"><span class=\"trp-ls-language-name\">EN<\/span><\/span><\/a><\/li>\n\t<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-1561\"><a href=\"https:\/\/visit-sibenik.com\/fr\/wp-json\/wp\/v2\/pages\/481#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor\"><span data-no-translation><img loading=\"lazy\" decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/visit-sibenik.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/de_DE.png\" width=\"18\" height=\"12\" alt=\"de_DE\" title=\"German\"><span class=\"trp-ls-language-name\">DE<\/span><\/span><\/a><\/li>\n\t<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-1562\"><a href=\"https:\/\/visit-sibenik.com\/fr\/wp-json\/wp\/v2\/pages\/481#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor\"><span data-no-translation><img loading=\"lazy\" decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/visit-sibenik.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/hr.png\" width=\"18\" height=\"12\" alt=\"hr\" title=\"Croatian\"><span class=\"trp-ls-language-name\">HR<\/span><\/span><\/a><\/li>\n\t<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-1560\"><a href=\"https:\/\/visit-sibenik.com\/fr\/wp-json\/wp\/v2\/pages\/481#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor\"><span data-no-translation><img loading=\"lazy\" decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/visit-sibenik.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/cs_CZ.png\" width=\"18\" height=\"12\" alt=\"cs_CZ\" title=\"Czech\"><span class=\"trp-ls-language-name\">CS<\/span><\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Permuter le menu\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-15d80cfb\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-85\"><a href=\"https:\/\/visit-sibenik.com\/fr\/\" class=\"elementor-item\" tabindex=\"-1\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-877\"><a href=\"https:\/\/visit-sibenik.com\/fr\/adventures\/\" class=\"elementor-item\" tabindex=\"-1\">Adventures<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1694\"><a href=\"https:\/\/visit-sibenik.com\/fr\/new-speedboat-tour-with-anima-natura\/\" class=\"elementor-sub-item\" tabindex=\"-1\">NEW! Speedboat Tour with Anima Natura<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-509\"><a href=\"https:\/\/visit-sibenik.com\/fr\/speed-boat-tour-krka\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Speed Boat Tour to Krka<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-508\"><a href=\"https:\/\/visit-sibenik.com\/fr\/speed-boat-tour-kornati\/\" class=\"elementor-sub-item\" tabindex=\"-1\">NP Kornati Speed boat tour<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-507\"><a href=\"https:\/\/visit-sibenik.com\/fr\/riviera-tour-zlarin-prvic-tijat\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Riviera Tour: Zlarin + Prvi\u0107 + Tijat<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-506\"><a href=\"https:\/\/visit-sibenik.com\/fr\/swimming-tour\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Swimming Tour<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1609\"><a href=\"https:\/\/visit-sibenik.com\/fr\/sibenik-lux-islands-picnic-boat-tour\/\" class=\"elementor-sub-item\" tabindex=\"-1\">\u0160ibenik Lux Islands Picnic Boat Tour<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1608\"><a href=\"https:\/\/visit-sibenik.com\/fr\/la-dolce-vita-tour-experience-the-dream-mediterranean\/\" class=\"elementor-sub-item\" tabindex=\"-1\">La Dolce Vita Tour \u2013 Experience the Dream Mediterranean!<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-505\"><a href=\"https:\/\/visit-sibenik.com\/fr\/panoramic-boat-tour\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Panoramic Boat Tour<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-504\"><a href=\"https:\/\/visit-sibenik.com\/fr\/private-boat-tour\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Private Boat Tour<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-503\"><a href=\"https:\/\/visit-sibenik.com\/fr\/kornati-big-boat\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Kornati Big Boat<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1204\"><a href=\"https:\/\/visit-sibenik.com\/fr\/krka-big-boat\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Krka Big Boat<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-789\"><a href=\"https:\/\/visit-sibenik.com\/fr\/blue-cave\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Blue Cave<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-502\"><a href=\"https:\/\/visit-sibenik.com\/fr\/plitvice-lakes\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Plitvice Lakes<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-501\"><a href=\"https:\/\/visit-sibenik.com\/fr\/roski-slap\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Ro\u0161ki Slap<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-500\"><a href=\"https:\/\/visit-sibenik.com\/fr\/sibenik-walking-tour\/\" class=\"elementor-sub-item\" tabindex=\"-1\">\u0160ibenik Walking Tour<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-499\"><a href=\"https:\/\/visit-sibenik.com\/fr\/wine-tasting\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Wine Tasting<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1093\"><a href=\"https:\/\/visit-sibenik.com\/fr\/event\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Event<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-83\"><a href=\"https:\/\/visit-sibenik.com\/fr\/accommodation\/\" class=\"elementor-item\" tabindex=\"-1\">Accommodation<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-416\"><a href=\"https:\/\/visit-sibenik.com\/fr\/transfers\/\" class=\"elementor-item\" tabindex=\"-1\">Transfers<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-818\"><a href=\"https:\/\/visit-sibenik.com\/fr\/rent-a-boat\/\" class=\"elementor-item\" tabindex=\"-1\">Rent a boat<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-81\"><a href=\"https:\/\/visit-sibenik.com\/fr\/prices\/\" class=\"elementor-item\" tabindex=\"-1\">Prices<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1676\"><a href=\"https:\/\/visit-sibenik.com\/fr\/about-us\/\" class=\"elementor-item\" tabindex=\"-1\">About us<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-82\"><a href=\"https:\/\/visit-sibenik.com\/fr\/contact\/\" class=\"elementor-item\" tabindex=\"-1\">Contact<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1042\"><a href=\"https:\/\/visit-sibenik.com\/fr\/news\/\" class=\"elementor-item\" tabindex=\"-1\">News<\/a><\/li>\n<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher menu-item-has-children current-language-menu-item menu-item-1565\"><a href=\"https:\/\/visit-sibenik.com\/fr\/wp-json\/wp\/v2\/pages\/481#TRPLINKPROCESSED\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\"><span data-no-translation><img decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/visit-sibenik.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/fr_FR.png\" width=\"18\" height=\"12\" alt=\"fr_FR\" title=\"French\"><span class=\"trp-ls-language-name\">FR<\/span><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-1566\"><a href=\"https:\/\/visit-sibenik.com\/fr\/wp-json\/wp\/v2\/pages\/481#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\"><span data-no-translation><img decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/visit-sibenik.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/en_GB.png\" width=\"18\" height=\"12\" alt=\"en_GB\" title=\"English\"><span class=\"trp-ls-language-name\">EN<\/span><\/span><\/a><\/li>\n\t<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-1561\"><a href=\"https:\/\/visit-sibenik.com\/fr\/wp-json\/wp\/v2\/pages\/481#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\"><span data-no-translation><img loading=\"lazy\" decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/visit-sibenik.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/de_DE.png\" width=\"18\" height=\"12\" alt=\"de_DE\" title=\"German\"><span class=\"trp-ls-language-name\">DE<\/span><\/span><\/a><\/li>\n\t<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-1562\"><a href=\"https:\/\/visit-sibenik.com\/fr\/wp-json\/wp\/v2\/pages\/481#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\"><span data-no-translation><img loading=\"lazy\" decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/visit-sibenik.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/hr.png\" width=\"18\" height=\"12\" alt=\"hr\" title=\"Croatian\"><span class=\"trp-ls-language-name\">HR<\/span><\/span><\/a><\/li>\n\t<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-1560\"><a href=\"https:\/\/visit-sibenik.com\/fr\/wp-json\/wp\/v2\/pages\/481#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\"><span data-no-translation><img loading=\"lazy\" decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/visit-sibenik.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/cs_CZ.png\" width=\"18\" height=\"12\" alt=\"cs_CZ\" title=\"Czech\"><span class=\"trp-ls-language-name\">CS<\/span><\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c0ca49a elementor-section-height-full elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"5c0ca49a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3d39a790\" data-id=\"3d39a790\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b198c3 elementor-widget elementor-widget-heading\" data-id=\"b198c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">Kornati Big Boat<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ea0f1cf elementor-widget elementor-widget-heading\" data-id=\"2ea0f1cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-large\">Join us and have a great time while exploring Kornati National Park. Relax and soak up all the positive energy that will fill you up while cruising this untouched nature beauty.<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ca33c0 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"8ca33c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/visit-sibenik.com\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Book Now<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-39501f3f elementor-section-height-min-height elementor-section-items-stretch elementor-section-full_width elementor-section-height-default\" data-id=\"39501f3f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-78b3df90\" data-id=\"78b3df90\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b540643 elementor-align-start elementor-widget__width-auto elementor-absolute elementor-hidden-phone elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"3b540643\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/web.facebook.com\/visitsibenik\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook-f\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/visitsibenik\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Capa_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 512 512\" style=\"enable-background:new 0 0 512 512;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M352,0H160C71.648,0,0,71.648,0,160v192c0,88.352,71.648,160,160,160h192c88.352,0,160-71.648,160-160V160    C512,71.648,440.352,0,352,0z M464,352c0,61.76-50.24,112-112,112H160c-61.76,0-112-50.24-112-112V160C48,98.24,98.24,48,160,48    h192c61.76,0,112,50.24,112,112V352z\"><\/path>\t<\/g><\/g><g>\t<g>\t\t<path d=\"M256,128c-70.688,0-128,57.312-128,128s57.312,128,128,128s128-57.312,128-128S326.688,128,256,128z M256,336    c-44.096,0-80-35.904-80-80c0-44.128,35.904-80,80-80s80,35.872,80,80C336,300.096,300.096,336,256,336z\"><\/path>\t<\/g><\/g><g>\t<g>\t\t<circle cx=\"393.6\" cy=\"118.4\" r=\"17.056\"><\/circle>\t<\/g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.youtube.com\/channel\/UCOdQaLgTP4WK7srvCwCrPuw\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5c184997\" data-id=\"5c184997\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1837c45d elementor-widget elementor-widget-heading\" data-id=\"1837c45d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Kornati Big Boat<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7a71ba elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b7a71ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 20 16&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;2.2&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cg transform=&#039;translate(-12.000000, 0)&#039;%3E%3Cpath d=&#039;M28,0L10,18&#039;\/%3E%3Cpath d=&#039;M18,0L0,18&#039;\/%3E%3Cpath d=&#039;M48,0L30,18&#039;\/%3E%3Cpath d=&#039;M38,0L20,18&#039;\/%3E%3C\/g%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c0534cb elementor-widget elementor-widget-heading\" data-id=\"5c0534cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">About the tour<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71a84c3e elementor-widget elementor-widget-text-editor\" data-id=\"71a84c3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Departure from Vodice. Sailing across the Murter Sea to the SE entrance to the Kornati National Park and a tour of the lower part of the Kornati archipelago. Exit to the open sea by sailing along vertical cliffs, the \u201ccrown\u201d of the Kornati islands that are the most striking phenomena of this National Park. Lunch on board. Continue the cruise alongside the church of Our Lady of Tarac and the Fortress of Tureta towards the Tela\u0161\u0107ica Nature Park on Dugi Otok.<\/p><p>Docking in Tela\u0161\u0107ica Bay. Free time for swimming, sunbathing and diving, a visit to the lookout point with an unforgettable view of the cliffs, a tour to the stone sculptures Skra\u010de, a hiking trail on karst stone \u201ccircles\u201d, a walk around Salt Lake Mir or to check out the wild donkey reserve.<\/p><p>Return by the Kornati archipelago\u2019s upper route throughout the pass of Mala Proversa with archaeological finds from the Roman times, and sailing across the \u017dut and Sita island group. Cruising the south side of the island of Murter, passing the fishing village of Tribunj. Return to Vodice.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-43ba9f40\" data-id=\"43ba9f40\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;2&quot;,&quot;sizes&quot;:[]},&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42a0b89c elementor-widget elementor-widget-spacer\" data-id=\"42a0b89c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f8974bc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f8974bc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-75acfa89\" data-id=\"75acfa89\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65f06940 elementor-widget elementor-widget-heading\" data-id=\"65f06940\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Itinerary \/ schedule<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3a6fb40b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3a6fb40b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-58f79425\" data-id=\"58f79425\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-398939c elementor-widget elementor-widget-heading\" data-id=\"398939c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">from 09:00h<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-324d72a3\" data-id=\"324d72a3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71952941 elementor-widget elementor-widget-heading\" data-id=\"71952941\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Check-in<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a6abbfa\" data-id=\"a6abbfa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f889f7 elementor-widget elementor-widget-heading\" data-id=\"5f889f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vodice Port<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-814979b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"814979b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d4f8d23\" data-id=\"d4f8d23\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54cc880 elementor-widget elementor-widget-heading\" data-id=\"54cc880\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">09:00h<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-120d232\" data-id=\"120d232\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35b58ce elementor-widget elementor-widget-heading\" data-id=\"35b58ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Departure<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-02c38e6\" data-id=\"02c38e6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be125da elementor-widget elementor-widget-heading\" data-id=\"be125da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vodice Port<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-57eb7a7d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"57eb7a7d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1a770ce8\" data-id=\"1a770ce8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-357f6f72 elementor-widget elementor-widget-heading\" data-id=\"357f6f72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">12:00h<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6a3e47a4\" data-id=\"6a3e47a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e580301 elementor-widget elementor-widget-heading\" data-id=\"5e580301\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Arrival<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-bf0c423\" data-id=\"bf0c423\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a18ec66 elementor-widget elementor-widget-heading\" data-id=\"a18ec66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nature Park Tela\u0161\u0107ica<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7c268ab7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7c268ab7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5385ce08\" data-id=\"5385ce08\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-262884bf elementor-widget elementor-widget-heading\" data-id=\"262884bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">14:45h<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7c86eb5b\" data-id=\"7c86eb5b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a275a29 elementor-widget elementor-widget-heading\" data-id=\"1a275a29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Departure<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7d3b5ec\" data-id=\"7d3b5ec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ba65a6 elementor-widget elementor-widget-heading\" data-id=\"7ba65a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nature Park Tela\u0161\u0107ica<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-161dd57d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"161dd57d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2b3d719f\" data-id=\"2b3d719f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27fb4797 elementor-widget elementor-widget-heading\" data-id=\"27fb4797\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">17:30h<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-39ee3ce2\" data-id=\"39ee3ce2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73f5162c elementor-widget elementor-widget-heading\" data-id=\"73f5162c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Return<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-cd5ad85\" data-id=\"cd5ad85\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c3254f elementor-widget elementor-widget-heading\" data-id=\"2c3254f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vodice Port<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-31ad29ab\" data-id=\"31ad29ab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-387b7b78 elementor-widget elementor-widget-heading\" data-id=\"387b7b78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Price<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15a4de09 elementor-widget elementor-widget-heading\" data-id=\"15a4de09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Per person 79,00 \u20ac<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ccba02c elementor-widget elementor-widget-heading\" data-id=\"3ccba02c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Included in price<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ff88595 elementor-widget elementor-widget-heading\" data-id=\"3ff88595\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Transportation<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12fd42ed elementor-widget elementor-widget-heading\" data-id=\"12fd42ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lunch on boat<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c1d7c6 elementor-widget elementor-widget-heading\" data-id=\"8c1d7c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Entrance ticket to Kornati National Park<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7de18a6b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7de18a6b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66cd569e\" data-id=\"66cd569e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33545850 elementor-widget elementor-widget-heading\" data-id=\"33545850\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Get a better view <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-478bba4e elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"478bba4e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6265d467\" data-id=\"6265d467\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18920cd3 elementor-skin-coverflow elementor-arrows-yes elementor-pagination-type-bullets elementor-pagination-position-outside elementor-widget elementor-widget-media-carousel\" data-id=\"18920cd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;skin&quot;:&quot;coverflow&quot;,&quot;slides_to_scroll&quot;:&quot;3&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"kornati-new\" style=\"background-image: url(&#039;https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/kornati-new-1-scaled.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"kornati-new\" style=\"background-image: url(&#039;https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/kornati-new.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"resize_kornati-new-2-tiny\" style=\"background-image: url(&#039;https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/resize_kornati-new-2-tiny-scaled.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"IMG-20200217-WA0004 (1)\" style=\"background-image: url(&#039;https:\/\/visit-sibenik.com\/wp-content\/uploads\/2021\/07\/IMG-20200217-WA0004-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-32f17ffb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"32f17ffb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a68f30b\" data-id=\"a68f30b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7992cb1e elementor-widget elementor-widget-heading\" data-id=\"7992cb1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">See our other adventures<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1247228 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1247228\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3a9c2931\" data-id=\"3a9c2931\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-574fca65 elementor-grid-6 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-portfolio\" data-id=\"574fca65\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:&quot;6&quot;,&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;item_ratio&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;item_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"portfolio.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-portfolio elementor-grid elementor-posts-container\" role=\"list\">\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-485 page type-page status-publish has-post-thumbnail hentry entry has-media\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/visit-sibenik.com\/fr\/roski-slap\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_roski-slap-tiny-1024x683.jpg\" class=\"attachment-large size-large wp-image-904\" alt=\"\" srcset=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_roski-slap-tiny-1024x683.jpg 1024w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_roski-slap-tiny-300x200.jpg 300w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_roski-slap-tiny-768x512.jpg 768w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_roski-slap-tiny-1536x1024.jpg 1536w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_roski-slap-tiny-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tRo\u0161ki Slap\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-475 page type-page status-publish has-post-thumbnail hentry entry has-media\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/visit-sibenik.com\/fr\/swimming-tour\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"691\" height=\"1024\" src=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib2-691x1024.jpg\" class=\"attachment-large size-large wp-image-899\" alt=\"\" srcset=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib2-691x1024.jpg 691w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib2-202x300.jpg 202w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib2-768x1139.jpg 768w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib2-1036x1536.jpg 1036w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib2-1381x2048.jpg 1381w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib2-scaled.jpg 1726w\" sizes=\"(max-width: 691px) 100vw, 691px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tSwimming Tour\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-477 page type-page status-publish has-post-thumbnail hentry entry has-media\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/visit-sibenik.com\/fr\/panoramic-boat-tour\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1019\" src=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/Screenshot_20200605_112602-1024x1019.jpg\" class=\"attachment-large size-large wp-image-943\" alt=\"\" srcset=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/Screenshot_20200605_112602-1024x1019.jpg 1024w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/Screenshot_20200605_112602-300x300.jpg 300w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/Screenshot_20200605_112602-150x150.jpg 150w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/Screenshot_20200605_112602-768x764.jpg 768w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/Screenshot_20200605_112602.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPanoramic Boat Tour\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-479 page type-page status-publish has-post-thumbnail hentry entry has-media\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/visit-sibenik.com\/fr\/private-boat-tour\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"749\" src=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/07\/Screenshot_20200629_122159-1024x749.jpg\" class=\"attachment-large size-large wp-image-1114\" alt=\"\" srcset=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/07\/Screenshot_20200629_122159-1024x749.jpg 1024w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/07\/Screenshot_20200629_122159-300x219.jpg 300w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/07\/Screenshot_20200629_122159-768x562.jpg 768w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/07\/Screenshot_20200629_122159.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPrivate Boat Tour\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-491 page type-page status-publish has-post-thumbnail hentry entry has-media\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/visit-sibenik.com\/fr\/fishing-trip-with-boat-and-kayaks\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"680\" src=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/fishing-trip-1024x680.jpg\" class=\"attachment-large size-large wp-image-218\" alt=\"\" srcset=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/fishing-trip-1024x680.jpg 1024w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/fishing-trip-300x199.jpg 300w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/fishing-trip-768x510.jpg 768w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/fishing-trip.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tFishing Trip With Boat And Kayaks\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-481 page type-page status-publish has-post-thumbnail hentry entry has-media\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/visit-sibenik.com\/fr\/kornati-big-boat\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/kornati-new-1-1024x682.jpg\" class=\"attachment-large size-large wp-image-773\" alt=\"\" srcset=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/kornati-new-1-1024x682.jpg 1024w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/kornati-new-1-300x200.jpg 300w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/kornati-new-1-768x512.jpg 768w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/kornati-new-1-1536x1023.jpg 1536w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/kornati-new-1-2048x1364.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tKornati Big Boat\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-471 page type-page status-publish has-post-thumbnail hentry entry has-media\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/visit-sibenik.com\/fr\/speed-boat-tour-kornati\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"709\" src=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib3-1024x709.jpg\" class=\"attachment-large size-large wp-image-901\" alt=\"\" srcset=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib3-1024x709.jpg 1024w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib3-300x208.jpg 300w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib3-768x532.jpg 768w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib3-1536x1063.jpg 1536w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib3-2048x1418.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tSpeed Boat Tour Kornati\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-483 page type-page status-publish has-post-thumbnail hentry entry has-media\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/visit-sibenik.com\/fr\/plitvice-lakes\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/plitvice_min-1024x682-1.jpg\" class=\"attachment-large size-large wp-image-200\" alt=\"\" srcset=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/plitvice_min-1024x682-1.jpg 1024w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/plitvice_min-1024x682-1-300x200.jpg 300w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/plitvice_min-1024x682-1-768x512.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPlitvice Lakes\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-786 page type-page status-publish has-post-thumbnail hentry entry has-media\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/visit-sibenik.com\/fr\/blue-cave\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/IMG_20200322_185512_720-1024x1024.jpg\" class=\"attachment-large size-large wp-image-1046\" alt=\"\" srcset=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/IMG_20200322_185512_720-1024x1024.jpg 1024w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/IMG_20200322_185512_720-300x300.jpg 300w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/IMG_20200322_185512_720-150x150.jpg 150w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/IMG_20200322_185512_720-768x768.jpg 768w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/IMG_20200322_185512_720.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tBlue Cave\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-487 page type-page status-publish has-post-thumbnail hentry entry has-media\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/visit-sibenik.com\/fr\/sibenik-walking-tour\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/3min-1024x575-1.jpg\" class=\"attachment-large size-large wp-image-189\" alt=\"\" srcset=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/3min-1024x575-1.jpg 1024w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/3min-1024x575-1-300x168.jpg 300w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/3min-1024x575-1-768x431.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\t\u0160ibenik Walking Tour\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-489 page type-page status-publish has-post-thumbnail hentry entry has-media\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/visit-sibenik.com\/fr\/wine-tasting\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"754\" src=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/Screenshot_20200605_115745-1024x754.jpg\" class=\"attachment-large size-large wp-image-921\" alt=\"\" srcset=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/Screenshot_20200605_115745-1024x754.jpg 1024w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/Screenshot_20200605_115745-300x221.jpg 300w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/Screenshot_20200605_115745-768x565.jpg 768w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/Screenshot_20200605_115745.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tWine Tasting\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-473 page type-page status-publish has-post-thumbnail hentry entry has-media\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/visit-sibenik.com\/fr\/riviera-tour-zlarin-prvic-tijat\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib1-768x1024.jpg\" class=\"attachment-large size-large wp-image-900\" alt=\"\" srcset=\"https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib1-768x1024.jpg 768w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib1-225x300.jpg 225w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib1-1152x1536.jpg 1152w, https:\/\/visit-sibenik.com\/wp-content\/uploads\/2020\/06\/rsz_sib1.jpg 1500w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tRiviera Tour: Zlarin + Prvi\u0107 + Tijat\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3e3183c2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3e3183c2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-12747ed7\" data-id=\"12747ed7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c137488 elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"3c137488\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Instagram<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-37d56643\" data-id=\"37d56643\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fc3b72f elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"5fc3b72f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-heart\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fdc1162 elementor-widget elementor-widget-heading\" data-id=\"7fdc1162\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Visit \u0160ibenik<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-466f631b elementor-widget elementor-widget-heading\" data-id=\"466f631b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0160IBENIK is an adventure waiting to happen. It is a town FULL OF LOVE. Be sure to book your guided tour with ANIMA NATURA today.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4240da38\" data-id=\"4240da38\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-359bbdf5 elementor-tablet-align-center elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"359bbdf5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook-f\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Facebook<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-299f5997 elementor-widget elementor-widget-facebook-page\" data-id=\"299f5997\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"facebook-page.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-facebook-widget fb-page\" data-href=\"https:\/\/web.facebook.com\/visitsibenik\/?_rdc=1&amp;_rdr\" data-tabs=\"timeline\" data-height=\"350px\" data-width=\"500px\" data-small-header=\"false\" data-hide-cover=\"false\" data-show-facepile=\"true\" data-hide-cta=\"false\" style=\"min-height: 1px;height:350px\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Kornati Big Boat Join us and have a great time while exploring Kornati National Park. Relax and soak up all the positive energy that will fill you up while cruising this untouched nature beauty. Book Now Kornati Big Boat About the tour Departure from Vodice. Sailing across the Murter Sea to the SE entrance to [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":773,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ocean_post_layout":"full-screen","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"off","ocean_display_header":"off","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"on","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"off","ocean_display_footer_bottom":"off","ocean_custom_footer_template":"0","footnotes":""},"class_list":["post-481","page","type-page","status-publish","has-post-thumbnail","hentry","entry","has-media"],"_links":{"self":[{"href":"https:\/\/visit-sibenik.com\/fr\/wp-json\/wp\/v2\/pages\/481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit-sibenik.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/visit-sibenik.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/visit-sibenik.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visit-sibenik.com\/fr\/wp-json\/wp\/v2\/comments?post=481"}],"version-history":[{"count":39,"href":"https:\/\/visit-sibenik.com\/fr\/wp-json\/wp\/v2\/pages\/481\/revisions"}],"predecessor-version":[{"id":1658,"href":"https:\/\/visit-sibenik.com\/fr\/wp-json\/wp\/v2\/pages\/481\/revisions\/1658"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit-sibenik.com\/fr\/wp-json\/wp\/v2\/media\/773"}],"wp:attachment":[{"href":"https:\/\/visit-sibenik.com\/fr\/wp-json\/wp\/v2\/media?parent=481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}